{"id":160086,"date":"2018-03-02T06:14:53","date_gmt":"2018-03-02T05:14:53","guid":{"rendered":"https:\/\/www.bolsamania.com\/seriesadictos\/?p=160086"},"modified":"2018-03-02T06:14:53","modified_gmt":"2018-03-02T05:14:53","slug":"se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso","status":"publish","type":"post","link":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/","title":{"rendered":"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[117,11740,8539],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariabella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/#website\",\"url\":\"https:\/\/www.bolsamania.com\/seriesadictos\/\",\"name\":\"Series Adictos\",\"description\":\"Al d\\u00eda de las series m\\u00e1s rompedoras.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bolsamania.com\/seriesadictos\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg\",\"contentUrl\":\"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg\",\"width\":1000,\"height\":563},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#webpage\",\"url\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/\",\"name\":\"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos\",\"isPartOf\":{\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#primaryimage\"},\"datePublished\":\"2018-03-02T05:14:53+00:00\",\"dateModified\":\"2018-03-02T05:14:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/#\/schema\/person\/14688d4a42debc0a38d98016464303b6\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bolsamania.com\/seriesadictos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/#\/schema\/person\/14688d4a42debc0a38d98016464303b6\",\"name\":\"mariabella\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.bolsamania.com\/seriesadictos\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2b6403609fed9f3f52be99ca6a68def?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2b6403609fed9f3f52be99ca6a68def?s=96&d=mm&r=g\",\"caption\":\"mariabella\"},\"url\":\"https:\/\/www.bolsamania.com\/seriesadictos\/author\/mariabella\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/","twitter_card":"summary_large_image","twitter_title":"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos","twitter_image":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg","twitter_misc":{"Escrito por":"mariabella","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/#website","url":"https:\/\/www.bolsamania.com\/seriesadictos\/","name":"Series Adictos","description":"Al d\u00eda de las series m\u00e1s rompedoras.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bolsamania.com\/seriesadictos\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#primaryimage","inLanguage":"es","url":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg","contentUrl":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-content\/uploads\/2018\/03\/genius_s2_13-e1515862845653.jpg","width":1000,"height":563},{"@type":"WebPage","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#webpage","url":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/","name":"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso - Series Adictos","isPartOf":{"@id":"https:\/\/www.bolsamania.com\/seriesadictos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#primaryimage"},"datePublished":"2018-03-02T05:14:53+00:00","dateModified":"2018-03-02T05:14:53+00:00","author":{"@id":"https:\/\/www.bolsamania.com\/seriesadictos\/#\/schema\/person\/14688d4a42debc0a38d98016464303b6"},"breadcrumb":{"@id":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/2018\/03\/02\/se-lanza-nuevo-avance-de-la-segunda-temporada-de-genius-con-antonio-banderas-como-pablo-picasso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bolsamania.com\/seriesadictos\/"},{"@type":"ListItem","position":2,"name":"Se lanza nuevo avance de la segunda temporada de Genius, con Antonio Banderas como Pablo Picasso"}]},{"@type":"Person","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/#\/schema\/person\/14688d4a42debc0a38d98016464303b6","name":"mariabella","image":{"@type":"ImageObject","@id":"https:\/\/www.bolsamania.com\/seriesadictos\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/d2b6403609fed9f3f52be99ca6a68def?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2b6403609fed9f3f52be99ca6a68def?s=96&d=mm&r=g","caption":"mariabella"},"url":"https:\/\/www.bolsamania.com\/seriesadictos\/author\/mariabella\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/posts\/160086"}],"collection":[{"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/comments?post=160086"}],"version-history":[{"count":0,"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/posts\/160086\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/media?parent=160086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/categories?post=160086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bolsamania.com\/seriesadictos\/wp-json\/wp\/v2\/tags?post=160086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}