{"id":9858,"date":"2015-11-02T06:30:13","date_gmt":"2015-11-02T05:30:13","guid":{"rendered":"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/?p=9858"},"modified":"2015-11-02T06:30:13","modified_gmt":"2015-11-02T05:30:13","slug":"orden-de-prelacion-y-de-embargo-de-bienes","status":"publish","type":"post","link":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/orden-de-prelacion-y-de-embargo-de-bienes\/","title":{"rendered":"El orden en que te embargar\u00e1n tus bienes"},"content":{"rendered":"<h2>Cuando incurrimos en un impago el deudor tendr\u00e1 derecho a reclamar lo que se adeuda. Este es el orden en el que se ejecutar\u00e1n tus bienes en caso de embargo.<\/h2>\n<p>La ley tiende a perseguir a quien no paga sus deudas, aunque siempre es m\u00e1s f\u00e1cil cuando el acreedor es el Estado, como por ejemplo cuando acumulas deudas con tu ayuntamiento o, todav\u00eda peor, con Hacienda. Si llega a darse el caso debes saber que <strong>existe un orden de ejecuci\u00f3n en los embargos, denominado orden de prelaci\u00f3n<\/strong>. \u00c9ste marcar\u00e1 qu\u00e9 activos se embargar\u00e1n en primer lugar.<\/p>\n<p>La prioridad en todo proceso judicial que incluya reclamaci\u00f3n de deuda y embargo de bienes ser\u00e1 que el acreedor cobre cuanto antes. Por eso mismo, el orden de prelaci\u00f3n &#8216;atacar\u00e1&#8217; primero a los bienes m\u00e1s l\u00edquidos, los que antes pueden convertirse en dinero contante y sonante.<\/p>\n<p class=\"alignnone\" title=\"Qu\u00e9 es el orden de prelaci\u00f3n\"><a href=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/08\/que-es-usura.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-8301\" src=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/08\/que-es-usura.jpg\" alt=\"qu\u00e9 es la usura y sus l\u00edmites\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/08\/que-es-usura.jpg 500w, https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/08\/que-es-usura-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a> <a href=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/11\/orden_de_prelacion.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-9859\" src=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/11\/orden_de_prelacion.jpg\" alt=\"Qu\u00e9 es el orden de prelaci\u00f3n\" width=\"500\" height=\"334\" srcset=\"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/11\/orden_de_prelacion.jpg 500w, https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-content\/uploads\/2015\/11\/orden_de_prelacion-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Pero la Ley tambi\u00e9n establece que deben ejecutarse y venderse primero los bienes del deudor que menor perjuicio le ocasionen, as\u00ed como los menos necesarios y m\u00e1s superfluos. Para entendernos, tu coche no ser\u00e1 lo primero que ejecuten si consideran que te es m\u00e1s o menos necesario para tu d\u00eda a d\u00eda y menos todav\u00eda si lo usas dentro de tu trabajo.<\/p>\n<h3>El orden de prelaci\u00f3n<\/h3>\n<p>Con estas ideas claras, el orden de prelaci\u00f3n que se sigue en los procesos de embargo es el siguiente:<\/p>\n<ul>\n<li>Dinero en efectivo o cuentas corrientes que el intervenido tenga en entidades bancarias.<\/li>\n<li>Cr\u00e9ditos, derechos a corto plazo, t\u00edtulos, valores o instrumentos financieros admitidos a negociaci\u00f3n en un mercado de valores.<\/li>\n<li>Alhajas, joyas, antig\u00fcedades y objetos de arte.<\/li>\n<li>Rentas, intereses y frutos de toda especie.<\/li>\n<li>Bienes muebles o semovientes. Estos \u00faltimos son los animales que puedan tener un valor determinado, que integren o formen ganader\u00edas\u2026 Tambi\u00e9n acciones, t\u00edtulos o valores no admitidas a cotizaci\u00f3n oficial y participaciones en sociedades.<\/li>\n<li>Bienes inmuebles, sean estos r\u00fasticos o urbanos.<\/li>\n<li>Sueldos, pensiones e ingresos procedentes de actividades profesionales y mercantiles ejercidas en calidad de aut\u00f3nomo.<\/li>\n<li>Cr\u00e9ditos, derechos, valores\u2026 cuando sean realizables a medio y largo plazo.<\/li>\n<\/ul>\n<p>Adem\u00e1s, conviene recordar que en el caso de los salarios existe un l\u00edmite a las cantidades que pueden embargarse, como tambi\u00e9n existen determinado tipo de bienes que no podr\u00e1n ejecutarse en caso de concurso.<\/p>\n<p><strong>Tambi\u00e9n te puede interesar<\/strong><\/p>\n<p><a href=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/cantidades-maximas-que-hacienda-puede-embargar-de-tu-salario\/\">Cantidades m\u00e1ximas que Hacienda pueda embargar de tu sueldo<\/a><\/p>\n<p><a href=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/puede-hacienda-embargarme-la-devolucion-de-la-renta\/\">\u00bfPuede Hacienda embargarte la devoluci\u00f3n de la renta?<\/a><\/p>\n<p><a href=\"http:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/que-se-considera-usura\/\">Qu\u00e9 se considera usura en Espa\u00f1a<\/a><\/p>\n<p>Imagen &#8211;\u00a0<a href=\"http:\/\/www.shutterstock.com\/gallery-2506606p1.html\">3dkombinat<\/a>\u00a0en Shutterstock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando incurrimos en un impago el deudor tendr\u00e1 derecho a reclamar lo que se adeuda. Este es el orden en el que se ejecutar\u00e1n tus bienes en caso de embargo. La ley tiende a perseguir a quien no paga sus deudas, aunque siempre es m\u00e1s f\u00e1cil cuando el acreedor es el Estado, como por ejemplo &hellip; <a class=\"readmore\" href=\"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/orden-de-prelacion-y-de-embargo-de-bienes\/\">Leer<\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[70],"tags":[1616,1606,1626,1619,1610,1605,1585,1582,1586,1591,1594,1602,1624,1599,1622,1607,1601,1615,1589,1611,1597,1613,1587,1608,1617,1612,1592,1620,1625,1628,1590,1588,1600,1603,1621,1627,1604,1593,1595,1623,1629,1609,1598,1584,1583,1614,1596,1618],"views":58944,"_links":{"self":[{"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/posts\/9858"}],"collection":[{"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/comments?post=9858"}],"version-history":[{"count":0,"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/posts\/9858\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/media?parent=9858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/categories?post=9858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bolsamania.com\/declaracion-impuestos-renta\/wp-json\/wp\/v2\/tags?post=9858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}